{"id":8397,"date":"2024-06-18T20:36:06","date_gmt":"2024-06-18T18:36:06","guid":{"rendered":"https:\/\/godunaserbien.com\/legal-forms-of-companies-in-serbia\/"},"modified":"2026-04-17T13:09:24","modified_gmt":"2026-04-17T11:09:24","slug":"unternehmen-in-serbien","status":"publish","type":"post","link":"https:\/\/godunaserbien.com\/de\/unternehmen-in-serbien\/","title":{"rendered":"Formen der Unternehmen in Serbien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8397\" class=\"elementor elementor-8397 elementor-7767\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-041a6f5 e-flex e-con-boxed e-con e-parent\" data-id=\"041a6f5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98074ae elementor-widget elementor-widget-jkit_post_featured_image\" data-id=\"98074ae\" data-element_type=\"widget\" data-widget_type=\"jkit_post_featured_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-featured-image jeg_module___6a04cfbde92cb\" ><div class=\"post-featured-image \"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Unternehmer in Serbien\" srcset=\"https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-1024x768.webp 1024w, https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-300x225.webp 300w, https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-768x576.webp 768w, https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-900x675.webp 900w, https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien-600x450.webp 600w, https:\/\/godunaserbien.com\/wp-content\/uploads\/2024\/06\/unternehmer-in-serbien.webp 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f84c16c e-flex e-con-boxed e-con e-parent\" data-id=\"f84c16c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd1809e elementor-widget elementor-widget-heading\" data-id=\"fd1809e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Unternehmensformen in Serbien<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83348f1 e-flex e-con-boxed e-con e-parent\" data-id=\"83348f1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c56e78 elementor-widget elementor-widget-text-editor\" data-id=\"9c56e78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Rechtsformen der Unternehmen in Serbien sind Arten von Gesch\u00e4ftsformen, durch die man Gesch\u00e4ftsaktivit\u00e4ten durchf\u00fchren kann. In Serbien gibt es sieben m\u00f6gliche Rechtsformen der Unternehmen:<\/p>\n<ul>\n<li>Personengesellschaft;<\/li>\n<li>Kommanditgesellschaft;<\/li>\n<li>Gesellschaft mit beschr\u00e4nkter Haftung;<\/li>\n<li>Aktiengesellschaft;<\/li>\n<li>Zweigniederlassung einer ausl\u00e4ndischen juristischen Person;<\/li>\n<li>Vertretung;<\/li>\n<li>Unternehmer (Einzelunternehmer).<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a40c3b e-flex e-con-boxed e-con e-parent\" data-id=\"9a40c3b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4ef43 elementor-widget elementor-widget-heading\" data-id=\"5c4ef43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Personengesellschaft<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47aaffa elementor-widget elementor-widget-text-editor\" data-id=\"47aaffa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Eine Personengesellschaft ist eine Rechtsform, die aus zwei oder mehr Gesellschaftern besteht. Sie haften gesamtschuldnerisch und zu gleichen Teilen mit ihrem gesamten Verm\u00f6gen f\u00fcr die Verbindlichkeiten der Personengesellschaft. Enth\u00e4lt der Gesellschaftsvertrag oder eine andere Vereinbarung zwischen den Gesellschaftern eine Bestimmung, die ihre Haftung gegen\u00fcber Dritten beschr\u00e4nkt, hat diese Bestimmung keine Rechtswirkung. Eine juristische Person kann Mitglied einer Personengesellschaft sein. Es gilt die Regel, dass die Gesellschafter gleiche Beitr\u00e4ge zum Unternehmen in Serbien leisten. Wenn ein Gesellschafter etwas tun oder entscheiden m\u00f6chte, ben\u00f6tigt er die Zustimmung aller anderen Gesellschafter.<\/p>\n<p>Der Gewinn einer Personengesellschaft wird zu gleichen Teilen unter den Gesellschaftern aufgeteilt, dies kann jedoch durch die Gr\u00fcndungsvereinbarung anders geregelt werden.<\/p>\n<p>Die Personengesellschaft ist als Form einer Unternehmen in Serbien h\u00e4ufig\u00a0<span style=\"color: var( --e-global-color-0361895 ); text-align: var(--text-align);\">nicht\u00a0<\/span><span style=\"font-size: inherit; color: var( --e-global-color-0361895 ); text-align: var(--text-align);\">vertreten.<\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d79b517 elementor-widget elementor-widget-heading\" data-id=\"d79b517\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kommanditgesellschaft<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a838ee9 elementor-widget elementor-widget-text-editor\" data-id=\"a838ee9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Eine Kommanditgesellschaft ist eine der sieben Rechtsformen von Unternehmen in Serbien, die von mindestens zwei Gr\u00fcndern gegr\u00fcndet werden \u2013 Komplement\u00e4ren und Kommanditisten. Eine Kommanditgesellschaft muss mindestens einen Komplement\u00e4r und mindestens einen Kommanditisten haben. Der Komplement\u00e4r ist der Gr\u00fcnder, der f\u00fcr einen unbestimmten Zeitraum und mit seinem gesamten Verm\u00f6gen f\u00fcr die Verpflichtungen des Unternehmens haftet. Der Kommanditist ist ein anderer Gr\u00fcnder, der f\u00fcr die Verpflichtungen des Unternehmens im Verh\u00e4ltnis zur H\u00f6he seines Beitrags haftet (er haftet daher nicht mit seinem pers\u00f6nlichen Verm\u00f6gen).<\/p>\n<p>Daher ist die Kommanditgesellschaft unter Formen der Unternehmen in Serbien der nicht oft als Rechtsform vertreten.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7618236 elementor-widget elementor-widget-heading\" data-id=\"7618236\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gesellschaft mit beschr\u00e4nkter Haftung<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf5a1a elementor-widget elementor-widget-text-editor\" data-id=\"bbf5a1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Die Gesellschaft mit beschr\u00e4nkter Haftung (GmbH) ist die h\u00e4ufigste Rechtsform der Unternehmen in Serbien. Die H\u00f6he der Einlagen der Gr\u00fcnder und Mitglieder in der Gesellschaft mit beschr\u00e4nkter Haftung muss in Serbien nicht gleich sein.<\/p>\n<p>Die Mitglieder einer GmbH haften f\u00fcr die Verpflichtungen des Unternehmens nur bis zur H\u00f6he ihres Anteils. Dies bedeutet, dass sie bis zur H\u00f6he des eingezahlten oder eingebrachten Anteils haften. Sie haften nicht f\u00fcr die Verpflichtungen des Unternehmens in Bezug auf ihr pers\u00f6nliches Eigentum, tragen jedoch das Risiko im Verh\u00e4ltnis zur H\u00f6he ihres Anteils.<\/p>\n<p>Eine GmbH ist eine Art der Unternehmen in Serbien, das einen oder mehrere Gr\u00fcnder haben kann. Jedes Mitglied hat einen Anteil am Aktienkapital des Unternehmens. Das Aktienkapital einer Gesellschaft mit beschr\u00e4nkter Haftung besteht aus der Summe der Einlagen der Gr\u00fcnder (in Form von Geld- und Sacheinlagen). Die H\u00f6he der Einlagen der Gr\u00fcnder und Mitglieder an die GmbH muss nicht gleich sein. Der Mindestbetrag des Aktienkapitals der Gesellschaft mit beschr\u00e4nkter Haftung betr\u00e4gt 100 Dinar (etwas weniger als 1 Euro).<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5979bad elementor-widget elementor-widget-heading\" data-id=\"5979bad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aktiengesellschaft<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e2341 elementor-widget elementor-widget-text-editor\" data-id=\"f2e2341\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Eine Aktiengesellschaft ist eine Form der Unternehmen in Serbien, deren Aktienkapital aus Aktien besteht. Aktion\u00e4re sind Eigent\u00fcmer der Aktien des Unternehmens und haben Anspruch auf Dividenden auf Grundlage ihrer Aktien. Sie haben au\u00dferdem das Recht, an der Entscheidung \u00fcber die Wahl des Managements mitzuwirken, sowie das Recht auf einen Teil des Liquidationsverm\u00f6gens im Falle einer Liquidation. Der Mindestwert des Aktienkapitals einer Aktiengesellschaft betr\u00e4gt 3.000.000 Dinar (ca. 25.000 Euro).<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d966e47 elementor-widget elementor-widget-heading\" data-id=\"d966e47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zweigniederlassung einer ausl\u00e4ndischen juristischen Person<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d94d83 elementor-widget elementor-widget-text-editor\" data-id=\"5d94d83\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Eine Niederlassung einer ausl\u00e4ndischen juristischen Person ist ein separater organisatorischer Teil eines ausl\u00e4ndischen Unternehmens, \u00fcber den dieses in der Republik Serbien t\u00e4tig ist. Sie hat ihre eingetragene Hauptt\u00e4tigkeit, kann aber auch alle anderen T\u00e4tigkeiten aus\u00fcben, die gesetzlich nicht verboten sind. Die Hauptt\u00e4tigkeit der Niederlassung und die Hauptt\u00e4tigkeit des Gr\u00fcndungsunternehmens m\u00fcssen nicht identisch sein.<\/p>\n<p>Die Niederlassung muss einen eigenen gesetzlichen Vertreter haben. Eine Niederlassung von einem ausl\u00e4ndischen Unternehmen in Serbien hat nicht den Status einer juristischen Person, sondern f\u00fchrt Handlungen und Handlungen im Namen der Gr\u00fcnder durch. Der Gr\u00fcnder der Niederlassung ist ein ausl\u00e4ndisches Unternehmen, das f\u00fcr das Gesch\u00e4ft der Niederlassung verantwortlich ist. Aus steuerlicher Sicht hat die Niederlassung den Status eines inl\u00e4ndischen Steuerans\u00e4ssigen.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f069e5d elementor-widget elementor-widget-heading\" data-id=\"f069e5d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vertretung<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3047ab elementor-widget elementor-widget-text-editor\" data-id=\"a3047ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3047ab elementor-widget elementor-widget-text-editor\" data-id=\"a3047ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Die Vertretung einer ausl\u00e4ndischen juristischen Person ist ein separater organisatorischer Teil des ausl\u00e4ndischen Unternehmens in Serbien, der vorbereitende T\u00e4tigkeiten durchf\u00fchren kann. Die Repr\u00e4sentanz hat nicht den Status einer juristischen Person. Obwohl die Vertretung au\u00dfer vorbereitenden T\u00e4tigkeiten keine Aktivit\u00e4ten des Gr\u00fcnders durchf\u00fchrt, muss die Vertretung in Serbien registriert sein. Die Arbeit der Vertretung unterliegt Beschr\u00e4nkungen, d. h. sie kann keine regul\u00e4ren Gesch\u00e4ftst\u00e4tigkeiten aus\u00fcben. Das hei\u00dft, sie kann keine Waren oder Dienstleistungen auf dem Markt verkaufen. Die Vertretung kann nur vorbereitende Transaktionen im Zusammenhang mit ihrem laufenden Gesch\u00e4ft abschlie\u00dfen (z. B. Annahme von Auftr\u00e4gen).<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45b05c7 elementor-widget elementor-widget-heading\" data-id=\"45b05c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Unternehmer (Einzelunternehmer)<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff93e73 elementor-widget elementor-widget-text-editor\" data-id=\"ff93e73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ein Unternehmer ist eine nat\u00fcrliche Person, die sich registriert, um Gewinn zu erzielen. Ein Unternehmer kann selbst Gewinn erzielen oder andere Arbeitnehmer einstellen. Der Unternehmer ist f\u00fcr alle seine Aktivit\u00e4ten mit seinem gesamten Eigentum verantwortlich. Es gibt zwei verschiedene Arten von Unternehmern:<\/p>\n<ul>\n<li>Pauschalunternehmer;<\/li>\n<li>Unternehmer, der <a href=\"https:\/\/godunaserbien.com\/de\/buchhaltung-in-serbien\/\">B\u00fccher f\u00fchrt<\/a>.<\/li>\n<\/ul>\n<p>Ein Pauschalunternehmer ist eine Art von Unternehmer, der einen j\u00e4hrlichen Umsatz von bis zu 6 Millionen Dinar (rund 50.000 Euro) hat. Je nach Ort der Registrierung, Alter und Art der T\u00e4tigkeit wird der Unternehmer mit einem festen Betrag besteuert. Ein Unternehmer, der B\u00fccher f\u00fchrt,\u00a0ist ein Unternehmer, der einen Umsatz von mehr als 6 Millionen Dinar hat oder der sich von Beginn des Gesch\u00e4fts an dazu entscheidet, B\u00fccher zu f\u00fchren. Er wird entsprechend dem Gesch\u00e4ftsergebnis aus den B\u00fcchern besteuert.\u00a0<\/p>\n<p>Bitte beachten Sie, dass alle Rechtsformen von Unternehmen in Serbien bei der <a href=\"https:\/\/www.apr.gov.rs\/home.1435.html\" rel=\"nofollow noopener\" target=\"_blank\">serbischen Handelsregisteragentur<\/a>\u00a0registriert sind.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Formen der Unternehmen in Serbien sind Arten von Gesch\u00e4ftsformen, durch die man Gesch\u00e4ftsaktivit\u00e4ten durchf\u00fchren kann. In Serbien gibt es sieben m\u00f6gliche Rechtsformen f\u00fcr Unternehmen.<\/p>\n","protected":false},"author":1,"featured_media":10117,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buchhaltung"],"_links":{"self":[{"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/posts\/8397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/comments?post=8397"}],"version-history":[{"count":22,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/posts\/8397\/revisions"}],"predecessor-version":[{"id":10351,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/posts\/8397\/revisions\/10351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/media\/10117"}],"wp:attachment":[{"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/media?parent=8397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/categories?post=8397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godunaserbien.com\/de\/wp-json\/wp\/v2\/tags?post=8397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}